{"id":62937,"date":"2026-07-14T11:00:42","date_gmt":"2026-07-14T09:00:42","guid":{"rendered":"https:\/\/www.gonomadu.com\/?post_type=property&#038;p=62937"},"modified":"2026-07-14T11:05:25","modified_gmt":"2026-07-14T09:05:25","slug":"xabia-costa-blanca-neubau-villa-mit-blick-auf-das-meer-und-den-montgo","status":"publish","type":"property","link":"https:\/\/www.gonomadu.com\/de\/property\/xabia-costa-blanca-neubau-villa-mit-blick-auf-das-meer-und-den-montgo\/","title":{"rendered":"X\u00e0bia | Costa Blanca \u2013 Neubau-Villa mit Blick auf das Meer und den Montg\u00f3"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong>Beeindruckende neu gebaute mediterrane Villa mit beheiztem Pool, mehreren Terrassen, Fitnessbereich und Blick auf das Meer und den Montg\u00f3, nur wenige Minuten vom Strand Arenal entfernt.<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h4>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Diese neu gebaute Villa befindet sich in einer erstklassigen Lage in X\u00e0bia, wo das imposante Bergmassiv Montg\u00f3 auf das kristallklare Mittelmeer trifft. Hochwertige Ausstattung, darunter Fu\u00dfbodenheizung, Klimaanlage mit Heiz- und K\u00fchlfunktion, eine Cocinart-K\u00fcche mit MIELE-Ger\u00e4ten, doppelt verglaste Fenster und Fliesenb\u00f6den, sorgen f\u00fcr ganzj\u00e4hrigen Komfort. <br><strong>        <div class=\"rmwr-wrapper\" \n             data-id=\"rmwr-6a56d9db7ac22\"\n             data-mode=\"normal\"\n             data-animation=\"fade\"\n             data-duration=\"300\"\n             data-smooth-scroll=\"true\"\n             data-scroll-offset=\"0\">\n            <button \n                type=\"button\"\n                class=\"read-link\" \n                id=\"readlinkrmwr-6a56d9db7ac22\"\n                data-open-text=\"Read More\"\n                data-close-text=\"Read Less\"\n                aria-expanded=\"false\"\n                aria-controls=\"readrmwr-6a56d9db7ac22\"\n                aria-label=\"Read More\"\n            >\n                <span class=\"rmwr-text\">Read More<\/span>\n            <\/button>\n            <div \n                class=\"read_div\" \n                id=\"readrmwr-6a56d9db7ac22\"\n                aria-hidden=\"true\"\n                data-animation=\"fade\"\n                data-duration=\"300\"\n                style=\"display: none;\"\n            >\n                <\/strong><br>Die gro\u00dfz\u00fcgigen, teilweise \u00fcberdachten Terrassen schaffen einen nahtlosen \u00dcbergang zwischen Innen- und Au\u00dfenbereich. Der beheizte Pool bietet an warmen Tagen erfrischende Momente, w\u00e4hrend ein privater Fitnessbereich mit optionaler Au\u00dfensauna sowie ein vielseitiger Hybridraum f\u00fcr G\u00e4ste, Homeoffice oder Heimkino zus\u00e4tzliche Flexibilit\u00e4t f\u00fcr bis zu 8 G\u00e4ste bieten. <br><br>Der Strand Platja de l&#8217;Arenal ist nur 5 Autominuten entfernt, der Hafen und die historische Altstadt von J\u00e1vea 10 Minuten, und der Golfclub X\u00e0bia sowie der Tennisclub J\u00e1vea nur 5 Minuten. Die Wanderwege des Naturparks Montg\u00f3 bieten au\u00dfergew\u00f6hnliche Outdoor-Abenteuer nur einen kurzen Weg von der Villa entfernt. <br><strong>            <\/div>\n        <\/div>\n        <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f7cb0fd8 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-e72d3f39\">\n<div class=\"wp-block-uagb-separator uagb-block-01ee8282 uag-hide-desktop uag-hide-tab uag-hide-mob\"><div class=\"uagb-separator-spacing-wrapper\"><div class=\"wp-block-uagb-separator__inner\" style=\"--my-background-image:\"><\/div><\/div><\/div>\n\n\n\n<div class=\"uagb-block-0dff694e uagb-infobox__content-wrap  uagb-infobox-icon-left-title uagb-infobox-left uagb-infobox-image-valign-middle \"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-left-title-image\"><div class=\"uagb-ifb-image-content\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.gonomadu.com\/wp-content\/uploads\/2025\/07\/ikona-a02.png\" alt=\"\" width=\"50\" height=\"50\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Neu gebaute mediterrane Villa<\/h5><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-separator uagb-block-96c43cb1\"><div class=\"uagb-separator-spacing-wrapper\"><div class=\"wp-block-uagb-separator__inner\" style=\"--my-background-image:\"><\/div><\/div><\/div>\n\n\n\n<div class=\"uagb-block-8f5bd569 uagb-infobox__content-wrap  uagb-infobox-icon-left-title uagb-infobox-left uagb-infobox-image-valign-middle \"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-left-title-image\"><div class=\"uagb-ifb-image-content\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.gonomadu.com\/wp-content\/uploads\/2025\/07\/ikona-a03.png\" alt=\"\" width=\"50\" height=\"50\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Blick auf das Meer und den Montg\u00f3<\/h5><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-separator uagb-block-071e7ba8\"><div class=\"uagb-separator-spacing-wrapper\"><div class=\"wp-block-uagb-separator__inner\" style=\"--my-background-image:\"><\/div><\/div><\/div>\n\n\n\n<div class=\"uagb-block-f3907581 uagb-infobox__content-wrap  uagb-infobox-icon-left-title uagb-infobox-left uagb-infobox-image-valign-middle \"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-left-title-image\"><div class=\"uagb-ifb-image-content\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.gonomadu.com\/wp-content\/uploads\/2025\/10\/ikona-a11.png\" alt=\"\" width=\"50\" height=\"50\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Mehrere Terrassen, teilweise \u00fcberdacht<\/h5><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-separator uagb-block-ae27b54f\"><div class=\"uagb-separator-spacing-wrapper\"><div class=\"wp-block-uagb-separator__inner\" style=\"--my-background-image:\"><\/div><\/div><\/div>\n\n\n\n<div class=\"uagb-block-b44d3826 uagb-infobox__content-wrap  uagb-infobox-icon-left-title uagb-infobox-left uagb-infobox-image-valign-middle \"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-left-title-image\"><div class=\"uagb-ifb-image-content\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.gonomadu.com\/wp-content\/uploads\/2025\/09\/ikona-a16.png\" alt=\"\" width=\"50\" height=\"50\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Gro\u00dfz\u00fcgiger beheizter Pool<\/h5><\/div><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-8b005355\">\n<div class=\"wp-block-uagb-separator uagb-block-8841b8da\"><div class=\"uagb-separator-spacing-wrapper\"><div class=\"wp-block-uagb-separator__inner\" style=\"--my-background-image:\"><\/div><\/div><\/div>\n\n\n\n<div class=\"uagb-block-9a30308c uagb-infobox__content-wrap  uagb-infobox-icon-left-title uagb-infobox-left uagb-infobox-image-valign-middle \"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-left-title-image\"><div class=\"uagb-ifb-image-content\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.gonomadu.com\/wp-content\/uploads\/2025\/07\/ikona-a25.png\" alt=\"\" width=\"50\" height=\"50\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Golf- und Tennisclub 5 Autominuten entfernt<\/h5><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-separator uagb-block-8873103c\"><div class=\"uagb-separator-spacing-wrapper\"><div class=\"wp-block-uagb-separator__inner\" style=\"--my-background-image:\"><\/div><\/div><\/div>\n\n\n\n<div class=\"uagb-block-732f517a uagb-infobox__content-wrap  uagb-infobox-icon-left-title uagb-infobox-left uagb-infobox-image-valign-middle \"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-left-title-image\"><div class=\"uagb-ifb-image-content\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.gonomadu.com\/wp-content\/uploads\/2025\/07\/ikona-a08.png\" alt=\"\" width=\"50\" height=\"50\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Strand Platja de l&#8217;Arenal 5 Autominuten entfernt<\/h5><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-separator uagb-block-04553612\"><div class=\"uagb-separator-spacing-wrapper\"><div class=\"wp-block-uagb-separator__inner\" style=\"--my-background-image:\"><\/div><\/div><\/div>\n\n\n\n<div class=\"uagb-block-cf35e07d uagb-infobox__content-wrap  uagb-infobox-icon-left-title uagb-infobox-left uagb-infobox-image-valign-middle \"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-left-title-image\"><div class=\"uagb-ifb-image-content\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.gonomadu.com\/wp-content\/uploads\/2025\/10\/ikona-a26.png\" alt=\"ikon\" width=\"50\" height=\"50\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Fitnessbereich und Au\u00dfensauna<\/h5><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-separator uagb-block-ea1d1ad3\"><div class=\"uagb-separator-spacing-wrapper\"><div class=\"wp-block-uagb-separator__inner\" style=\"--my-background-image:\"><\/div><\/div><\/div>\n\n\n\n<div class=\"uagb-block-0e93844b uagb-infobox__content-wrap  uagb-infobox-icon-left-title uagb-infobox-left uagb-infobox-image-valign-middle \"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-left-title-image\"><div class=\"uagb-ifb-image-content\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.gonomadu.com\/wp-content\/uploads\/2025\/07\/Restaurants-shops-nearby.png\" alt=\"\" width=\"50\" height=\"50\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Restaurants und Gesch\u00e4fte in fu\u00dfl\u00e4ufiger Entfernung<\/h5><\/div><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Snapshop d&#8217;investissement<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Die Costa Blanca ist mehr als nur ein Ausflugsziel \u2013 sie ist<strong> ein schnell wachsender, stark nachgefragter Markt<\/strong> mit solider Rendite. <strong>Neubauten verdoppeln oft ihren Wert<\/strong>, zum Beispiel von 150.000 \u20ac auf 240.000 \u20ac. Gleichzeitig sparen <strong>Miteigent\u00fcmer durchschnittlich \u00fcber 100.000 \u20ac<\/strong> bei Ferienvermietungen \u00fcber einen Zeitraum von 10 Jahren. Das ergibt einen ROI von <strong>250.000 \u20ac an kombiniertem Wert durch<\/strong> den Besitz eines realen, wertsteigernden Verm\u00f6genswerts.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Markt bietet eine stabile j\u00e4hrliche <strong>Rendite von 6\u20139 %<\/strong>, gest\u00fctzt durch begrenztes Angebot und internationale Nachfrage. Die Immobilienpreise steigen weiter, ohne Anzeichen einer Verlangsamung. Ihr Anteil gewinnt an Wert \u2013 w\u00e4hrend Sie luxuri\u00f6se Aufenthalte genie\u00dfen. Die Costa Blanca ist nicht nur ein Paradies \u2013 sie ist eine kluge <strong>Strategie zum Verm\u00f6gensaufbau.<\/strong>   <\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Standort &amp; Lebensstil<\/h4>\n\n\n\n<h5 class=\"wp-block-heading\">X\u00e0bia<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">X\u00e0bia ist das unangefochtene Juwel der Costa Blanca, wo das majest\u00e4tische Bergmassiv Montg\u00f3 auf das kristallklare Mittelmeer trifft. Die historische Altstadt verschmilzt mit der lebendigen Hafenatmosph\u00e4re und endlos sonnigen Tagen am Meer. Dank seines au\u00dfergew\u00f6hnlichen Mikroklimas, der abwechslungsreichen Landschaft und seines authentischen Charakters ist X\u00e0bia eines der begehrtesten Reiseziele an der spanischen K\u00fcste.  <\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-2f6d7bb6 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.gonomadu.com\/wp-content\/uploads\/2025\/07\/mapa-ob-16.png ,https:\/\/www.gonomadu.com\/wp-content\/uploads\/2025\/07\/mapa-ob-16.png 780w, https:\/\/www.gonomadu.com\/wp-content\/uploads\/2025\/07\/mapa-ob-16.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.gonomadu.com\/wp-content\/uploads\/2025\/07\/mapa-ob-16.png\" alt=\"\" class=\"uag-image-36964\" width=\"805\" height=\"684\" title=\"mapa-ob-16\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>D\u00e9nia | Costa Blanca | Spain &#8211; Spanien<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beeindruckende neu gebaute mediterrane Villa mit beheiztem Pool, mehreren Terrassen, Fitnessbereich und Blick auf das Meer und den Montg\u00f3, nur wenige Minuten vom Strand Arenal entfernt. Diese neu gebaute Villa befindet sich in einer erstklassigen Lage in X\u00e0bia, wo das imposante Bergmassiv Montg\u00f3 auf das kristallklare Mittelmeer trifft. Hochwertige Ausstattung, darunter Fu\u00dfbodenheizung, Klimaanlage mit Heiz- [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":62879,"parent":0,"menu_order":0,"template":"","property_type":[450],"property_status":[],"property_feature":[303,314,306,308,304,302,305,307,313,310,301,311,312,309,315],"property_label":[],"property_country":[],"property_state":[],"property_city":[1334,1348],"property_area":[],"class_list":["post-62937","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-villa-de","property_feature-barbecue","property_feature-dusche-im-freien","property_feature-fensterabdeckungen","property_feature-fitnessstudio","property_feature-klimatisierung","property_feature-kuhlschrank","property_feature-mikrowellenherd","property_feature-pad","property_feature-rasen","property_feature-sauna-de","property_feature-schwimmbad","property_feature-trockner","property_feature-tv-kabel","property_feature-wascherei","property_feature-wifi-de","property_city-costa-blanca-de","property_city-spain-de"],"property_meta":{"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:3;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:1;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:8;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:8;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"rank_math_internal_links_processed":["1"],"_last_translation_edit_mode":["native-editor"],"_elementor_template_type":["wp-post"],"_elementor_version":["3.29.2"],"houzez_featured_listing_date":["2026-07-14 11:05:25"],"_top_nav_excluded":[""],"_cms_nav_minihome":[""],"_wp_page_template":["default"],"fave_property_price":["299000"],"fave_property_price_prefix":["\u215b Anteil"],"fave_property_size":["187"],"fave_property_size_prefix":["m\u00b2"],"fave_property_land":["98"],"fave_property_land_postfix":["m\u00b2"],"fave_property_bedrooms":["4"],"fave_property_bathrooms":["3.5"],"fave_property_garage":["2"],"fave_property_year":["2026"],"fave_property_id":["NOMADU-0143"],"fave_property_map":["1"],"fave_property_map_address":["Q594+86G el Rafalet, Spain"],"fave_property_location":["38.7683125,0.1555781,8"],"houzez_geolocation_lat":["38.7683125"],"houzez_geolocation_long":["0.1555781"],"fave_property_map_street_view":["hide"],"fave_prop_homeslider":["no"],"floor_plans":["a:3:{i:0;a:2:{s:15:\"fave_plan_title\";s:23:\"Grundriss | Erdgeschoss\";s:15:\"fave_plan_image\";s:70:\"https:\/\/www.gonomadu.com\/wp-content\/uploads\/2026\/07\/lay-out-ob-188.png\";}i:1;a:2:{s:15:\"fave_plan_title\";s:24:\"Grundriss | Obergeschoss\";s:15:\"fave_plan_image\";s:70:\"https:\/\/www.gonomadu.com\/wp-content\/uploads\/2026\/07\/lay-out-ob-189.png\";}i:2;a:2:{s:15:\"fave_plan_title\";s:28:\"Grundriss | Unteres Geschoss\";s:15:\"fave_plan_image\";s:70:\"https:\/\/www.gonomadu.com\/wp-content\/uploads\/2026\/07\/lay-out-ob-190.png\";}}"],"_elementor_data":["[{\"id\":\"3e8ae0de\",\"elType\":\"container\",\"settings\":[],\"elements\":[{\"id\":\"219db2f\",\"elType\":\"widget\",\"settings\":{\"editor\":\"\\n<h4 class=\\\"wp-block-heading\\\">Modern new-build garden apartment with panoramic lake view, small garden, sunny terrace, home cinema, pool and hot tub, within walking distance of Lake Como<\\\/h4>\\n\\n\\n\\n<p><\\\/p>\\n\"},\"elements\":[],\"widgetType\":\"text-editor\"},{\"id\":\"6432e57\",\"elType\":\"widget\",\"settings\":[],\"elements\":[],\"widgetType\":\"icon\"},{\"id\":\"d5227d6\",\"elType\":\"widget\",\"settings\":[],\"elements\":[],\"widgetType\":\"icon\"}],\"isInner\":false}]"],"_thumbnail_id":["62879"],"_wpml_word_count":["521"],"_elementor_page_settings":[""],"_elementor_css":["a:6:{s:4:\"time\";i:1784011737;s:5:\"fonts\";a:0:{}s:5:\"icons\";a:1:{i:0;s:8:\"fa-solid\";}s:20:\"dynamic_elements_ids\";a:0:{}s:6:\"status\";s:0:\"\";i:0;s:0:\"\";}"],"_elementor_template_widget_type":[""],"_elementor_popup_display_settings":[""],"_elementor_controls_usage":["a:3:{s:11:\"text-editor\";a:3:{s:5:\"count\";i:1;s:15:\"control_percent\";i:0;s:8:\"controls\";a:1:{s:7:\"content\";a:1:{s:14:\"section_editor\";a:1:{s:6:\"editor\";i:1;}}}}s:4:\"icon\";a:3:{s:5:\"count\";i:2;s:15:\"control_percent\";i:0;s:8:\"controls\";a:0:{}}s:9:\"container\";a:3:{s:5:\"count\";i:1;s:15:\"control_percent\";i:0;s:8:\"controls\";a:0:{}}}"],"houzez_total_property_views":["2"],"houzez_views_by_date":["a:1:{s:10:\"07-14-2026\";i:2;}"],"houzez_recently_viewed":["2026-07-14 11:11:32"],"_elementor_page_assets":["a:1:{s:7:\"scripts\";a:1:{i:0;s:18:\"elementor-frontend\";}}"],"ekit_post_views_count":["2"],"_edit_lock":["1784019952:1"],"rank_math_seo_score":["10"],"_edit_last":["1"],"fave_show_price_placeholder":["0"],"houzez_manual_expire":["0"],"_houzez_expiration_date_status":["saved"],"fave_featured":["1"],"fave_property_images":["62876","62860","62868","62852"],"fave_agent_display_option":["agent_info"],"fave_agents":["156"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_uag_page_assets":["a:9:{s:3:\"css\";s:107116:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-separator{text-align:center;box-sizing:border-box;line-height:0}.wp-block-uagb-separator__inner{display:inline-block}.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{border-top-style:solid;-webkit-mask:var(--my-background-image);-webkit-mask-size:38px 100%;-webkit-mask-repeat:repeat-x}.wp-block-uagb-separator--text .wp-block-uagb-separator__inner,.wp-block-uagb-separator--icon .wp-block-uagb-separator__inner{display:flex;justify-content:center;align-items:center;margin:0 auto}.wp-block-uagb-separator--text .wp-block-uagb-separator__inner::before,.wp-block-uagb-separator--icon .wp-block-uagb-separator__inner::before{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top-color:#333;border-top-style:solid;-webkit-mask:var(--my-background-image);-webkit-mask-size:38px 100%;-webkit-mask-repeat:repeat-x}.wp-block-uagb-separator--text .wp-block-uagb-separator__inner::after,.wp-block-uagb-separator--icon .wp-block-uagb-separator__inner::after{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top-color:#333;border-top-style:solid;-webkit-mask:var(--my-background-image);-webkit-mask-size:38px 100%;-webkit-mask-repeat:repeat-x}.wp-block-uagb-separator--icon .wp-block-uagb-separator-element svg{font-size:30px;color:#333;fill:#333;width:30px;height:30px;line-height:30px;max-width:none}.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{word-break:initial;margin:0}.uagb-ifb-content>svg *{-webkit-transition:all .2s;-o-transition:all .2s;transition:all .2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=rtl] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=rtl] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:0;margin-left:10px}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:0;margin-right:10px}html[dir=rtl] .uagb-infobox-link-icon-after{margin-right:5px;margin-left:0}html[dir=rtl] .uagb-infobox-link-icon-before{margin-right:0;margin-left:5px}html[dir=rtl] .uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:left}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.wp-block-uagb-container.uagb-block-f7cb0fd8 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f7cb0fd8 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f7cb0fd8 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f7cb0fd8 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f7cb0fd8 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f7cb0fd8{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f7cb0fd8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-f7cb0fd8{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-e72d3f39 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e72d3f39 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e72d3f39 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e72d3f39 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e72d3f39 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e72d3f39{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e72d3f39 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-e72d3f39{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 20px;}.uagb-block-01ee8282.wp-block-uagb-separator{text-align: center;}.uagb-block-01ee8282.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;line-height: 1em;}.uagb-block-01ee8282 .uagb-separator-spacing-wrapper{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 10px;padding-right: 0px;padding-bottom: 10px;padding-left: 0px;}.uagb-block-01ee8282.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;border-top-width: 1px;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-0dff694e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-0dff694e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-0dff694e .uagb-ifb-icon svg{fill: #333;}.uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-0dff694e .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-0dff694e .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-0dff694e .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-0dff694e .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-0dff694e .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-0dff694e .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-0dff694e.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-0dff694e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-0dff694e .uagb-ifb-title{margin-bottom: 0px;margin-left: 20px;}.uagb-block-0dff694e .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-0dff694e .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-0dff694e .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-0dff694e .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-0dff694e .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-0dff694e .uagb-ifb-content .uagb-ifb-image-content > img{width: 50px;}.uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 50px;}.uagb-block-0dff694e .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 50px;}.uagb-block-0dff694e .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 50px;}.uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-0dff694e .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0dff694e.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0dff694e.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-0dff694e.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-96c43cb1.wp-block-uagb-separator{text-align: center;}.uagb-block-96c43cb1.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;line-height: 1em;}.uagb-block-96c43cb1 .uagb-separator-spacing-wrapper{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 10px;padding-right: 0px;padding-bottom: 10px;padding-left: 0px;}.uagb-block-96c43cb1.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;border-top-width: 1px;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-8f5bd569 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-8f5bd569 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-8f5bd569 .uagb-ifb-icon svg{fill: #333;}.uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8f5bd569 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8f5bd569 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8f5bd569 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8f5bd569 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8f5bd569 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8f5bd569 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-8f5bd569.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-8f5bd569 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-8f5bd569 .uagb-ifb-title{margin-bottom: 0px;margin-left: 20px;}.uagb-block-8f5bd569 .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-8f5bd569 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-8f5bd569 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-8f5bd569 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-8f5bd569 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8f5bd569 .uagb-ifb-content .uagb-ifb-image-content > img{width: 50px;}.uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 50px;}.uagb-block-8f5bd569 .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 50px;}.uagb-block-8f5bd569 .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 50px;}.uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-8f5bd569 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8f5bd569.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8f5bd569.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-8f5bd569.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-071e7ba8.wp-block-uagb-separator{text-align: center;}.uagb-block-071e7ba8.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;line-height: 1em;}.uagb-block-071e7ba8 .uagb-separator-spacing-wrapper{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 10px;padding-right: 0px;padding-bottom: 10px;padding-left: 0px;}.uagb-block-071e7ba8.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;border-top-width: 1px;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-f3907581 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-f3907581 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-f3907581 .uagb-ifb-icon svg{fill: #333;}.uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-f3907581 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-f3907581 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-f3907581 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-f3907581 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-f3907581 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-f3907581 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-f3907581.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-f3907581 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-f3907581 .uagb-ifb-title{margin-bottom: 0px;margin-left: 20px;}.uagb-block-f3907581 .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-f3907581 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-f3907581 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-f3907581 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-f3907581 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-f3907581 .uagb-ifb-content .uagb-ifb-image-content > img{width: 50px;}.uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 50px;}.uagb-block-f3907581 .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 50px;}.uagb-block-f3907581 .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 50px;}.uagb-block-f3907581.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-f3907581 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f3907581.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f3907581.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-f3907581.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-f3907581.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-ae27b54f.wp-block-uagb-separator{text-align: center;}.uagb-block-ae27b54f.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;line-height: 1em;}.uagb-block-ae27b54f .uagb-separator-spacing-wrapper{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 10px;padding-right: 0px;padding-bottom: 10px;padding-left: 0px;}.uagb-block-ae27b54f.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;border-top-width: 1px;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-b44d3826 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b44d3826 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-b44d3826 .uagb-ifb-icon svg{fill: #333;}.uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b44d3826 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b44d3826 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b44d3826 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b44d3826 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b44d3826 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b44d3826 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-b44d3826.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b44d3826 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-b44d3826 .uagb-ifb-title{margin-bottom: 0px;margin-left: 20px;}.uagb-block-b44d3826 .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-b44d3826 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-b44d3826 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-b44d3826 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-b44d3826 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b44d3826 .uagb-ifb-content .uagb-ifb-image-content > img{width: 50px;}.uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 50px;}.uagb-block-b44d3826 .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 50px;}.uagb-block-b44d3826 .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 50px;}.uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b44d3826 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b44d3826.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b44d3826.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-b44d3826.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-8b005355 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8b005355 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8b005355 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8b005355 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8b005355 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8b005355{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8b005355 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-8b005355{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 20px;}.uagb-block-8841b8da.wp-block-uagb-separator{text-align: center;}.uagb-block-8841b8da.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;line-height: 1em;}.uagb-block-8841b8da .uagb-separator-spacing-wrapper{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 10px;padding-right: 0px;padding-bottom: 10px;padding-left: 0px;}.uagb-block-8841b8da.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;border-top-width: 1px;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-9a30308c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-9a30308c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-9a30308c .uagb-ifb-icon svg{fill: #333;}.uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9a30308c .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9a30308c .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9a30308c .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9a30308c .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9a30308c .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9a30308c .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-9a30308c.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-9a30308c .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-9a30308c .uagb-ifb-title{margin-bottom: 0px;margin-left: 20px;}.uagb-block-9a30308c .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-9a30308c .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-9a30308c .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-9a30308c .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-9a30308c .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-9a30308c .uagb-ifb-content .uagb-ifb-image-content > img{width: 50px;}.uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 50px;}.uagb-block-9a30308c .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 50px;}.uagb-block-9a30308c .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 50px;}.uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-9a30308c .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9a30308c.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9a30308c.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-9a30308c.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-8873103c.wp-block-uagb-separator{text-align: center;}.uagb-block-8873103c.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;line-height: 1em;}.uagb-block-8873103c .uagb-separator-spacing-wrapper{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 10px;padding-right: 0px;padding-bottom: 10px;padding-left: 0px;}.uagb-block-8873103c.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;border-top-width: 1px;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-732f517a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-732f517a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-732f517a .uagb-ifb-icon svg{fill: #333;}.uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-732f517a .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-732f517a .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-732f517a .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-732f517a .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-732f517a .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-732f517a .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-732f517a.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-732f517a .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-732f517a .uagb-ifb-title{margin-bottom: 0px;margin-left: 20px;}.uagb-block-732f517a .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-732f517a .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-732f517a .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-732f517a .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-732f517a .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-732f517a .uagb-ifb-content .uagb-ifb-image-content > img{width: 50px;}.uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 50px;}.uagb-block-732f517a .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 50px;}.uagb-block-732f517a .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 50px;}.uagb-block-732f517a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-732f517a .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-732f517a.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-732f517a.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-732f517a.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-732f517a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-04553612.wp-block-uagb-separator{text-align: center;}.uagb-block-04553612.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;line-height: 1em;}.uagb-block-04553612 .uagb-separator-spacing-wrapper{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 10px;padding-right: 0px;padding-bottom: 10px;padding-left: 0px;}.uagb-block-04553612.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;border-top-width: 1px;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-cf35e07d .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-cf35e07d .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-cf35e07d .uagb-ifb-icon svg{fill: #333;}.uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-cf35e07d .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-cf35e07d .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-cf35e07d .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-cf35e07d .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-cf35e07d .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-cf35e07d .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-cf35e07d.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-cf35e07d .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-cf35e07d .uagb-ifb-title{margin-bottom: 0px;margin-left: 20px;}.uagb-block-cf35e07d .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-cf35e07d .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-cf35e07d .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-cf35e07d .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-cf35e07d .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-cf35e07d .uagb-ifb-content .uagb-ifb-image-content > img{width: 50px;}.uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 50px;}.uagb-block-cf35e07d .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 50px;}.uagb-block-cf35e07d .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 50px;}.uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-cf35e07d .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cf35e07d.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cf35e07d.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-cf35e07d.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-ea1d1ad3.wp-block-uagb-separator{text-align: center;}.uagb-block-ea1d1ad3.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;line-height: 1em;}.uagb-block-ea1d1ad3 .uagb-separator-spacing-wrapper{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 10px;padding-right: 0px;padding-bottom: 10px;padding-left: 0px;}.uagb-block-ea1d1ad3.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;border-top-width: 1px;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-0e93844b .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-0e93844b .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-0e93844b .uagb-ifb-icon svg{fill: #333;}.uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-0e93844b .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-0e93844b .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-0e93844b .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-0e93844b .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-0e93844b .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-0e93844b .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-0e93844b.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-0e93844b .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-0e93844b .uagb-ifb-title{margin-bottom: 0px;margin-left: 20px;}.uagb-block-0e93844b .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-0e93844b .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-0e93844b .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-0e93844b .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-0e93844b .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-0e93844b .uagb-ifb-content .uagb-ifb-image-content > img{width: 50px;}.uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 50px;}.uagb-block-0e93844b .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 50px;}.uagb-block-0e93844b .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 50px;}.uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-0e93844b .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0e93844b.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0e93844b.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-0e93844b.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-2f6d7bb6.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-2f6d7bb6.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-2f6d7bb6.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-2f6d7bb6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-2f6d7bb6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-2f6d7bb6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-2f6d7bb6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-2f6d7bb6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-2f6d7bb6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-2f6d7bb6.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-2f6d7bb6.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-2f6d7bb6.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-2f6d7bb6.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-2f6d7bb6.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-2f6d7bb6.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-f7cb0fd8{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f7cb0fd8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-f7cb0fd8{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e72d3f39{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e72d3f39 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-e72d3f39{padding-top: 0px;padding-bottom: 0px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-01ee8282.wp-block-uagb-separator{text-align: center;}.uagb-block-01ee8282.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-01ee8282.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-0dff694e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-0dff694e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-0dff694e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-0dff694e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0dff694e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0dff694e .uagb-ifb-content .uagb-ifb-image-content img{width: 50px;}.uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 50px;}.uagb-block-0dff694e .uagb-ifb-content .uagb-ifb-left-title-image img{width: 50px;}.uagb-block-0dff694e .uagb-ifb-content .uagb-ifb-right-title-image img{width: 50px;}.uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-96c43cb1.wp-block-uagb-separator{text-align: center;}.uagb-block-96c43cb1.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-96c43cb1.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8f5bd569 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-8f5bd569 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-8f5bd569 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-8f5bd569 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8f5bd569 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8f5bd569 .uagb-ifb-content .uagb-ifb-image-content img{width: 50px;}.uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 50px;}.uagb-block-8f5bd569 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 50px;}.uagb-block-8f5bd569 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 50px;}.uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-071e7ba8.wp-block-uagb-separator{text-align: center;}.uagb-block-071e7ba8.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-071e7ba8.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-f3907581 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-f3907581 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-f3907581 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-f3907581 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f3907581 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f3907581 .uagb-ifb-content .uagb-ifb-image-content img{width: 50px;}.uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 50px;}.uagb-block-f3907581 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 50px;}.uagb-block-f3907581 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 50px;}.uagb-block-f3907581.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-f3907581.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-ae27b54f.wp-block-uagb-separator{text-align: center;}.uagb-block-ae27b54f.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-ae27b54f.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b44d3826 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b44d3826 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b44d3826 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b44d3826 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b44d3826 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b44d3826 .uagb-ifb-content .uagb-ifb-image-content img{width: 50px;}.uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 50px;}.uagb-block-b44d3826 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 50px;}.uagb-block-b44d3826 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 50px;}.uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8b005355{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8b005355 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-8b005355{padding-top: 0px;padding-bottom: 0px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-8841b8da.wp-block-uagb-separator{text-align: center;}.uagb-block-8841b8da.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-8841b8da.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-9a30308c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-9a30308c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-9a30308c .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-9a30308c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9a30308c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9a30308c .uagb-ifb-content .uagb-ifb-image-content img{width: 50px;}.uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 50px;}.uagb-block-9a30308c .uagb-ifb-content .uagb-ifb-left-title-image img{width: 50px;}.uagb-block-9a30308c .uagb-ifb-content .uagb-ifb-right-title-image img{width: 50px;}.uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-8873103c.wp-block-uagb-separator{text-align: center;}.uagb-block-8873103c.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-8873103c.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-732f517a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-732f517a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-732f517a .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-732f517a .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-732f517a .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-732f517a .uagb-ifb-content .uagb-ifb-image-content img{width: 50px;}.uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 50px;}.uagb-block-732f517a .uagb-ifb-content .uagb-ifb-left-title-image img{width: 50px;}.uagb-block-732f517a .uagb-ifb-content .uagb-ifb-right-title-image img{width: 50px;}.uagb-block-732f517a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-732f517a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-04553612.wp-block-uagb-separator{text-align: center;}.uagb-block-04553612.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-04553612.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-cf35e07d .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-cf35e07d .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-cf35e07d .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-cf35e07d .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cf35e07d .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cf35e07d .uagb-ifb-content .uagb-ifb-image-content img{width: 50px;}.uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 50px;}.uagb-block-cf35e07d .uagb-ifb-content .uagb-ifb-left-title-image img{width: 50px;}.uagb-block-cf35e07d .uagb-ifb-content .uagb-ifb-right-title-image img{width: 50px;}.uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-ea1d1ad3.wp-block-uagb-separator{text-align: center;}.uagb-block-ea1d1ad3.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-ea1d1ad3.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-0e93844b .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-0e93844b .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-0e93844b .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-0e93844b .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0e93844b .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0e93844b .uagb-ifb-content .uagb-ifb-image-content img{width: 50px;}.uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 50px;}.uagb-block-0e93844b .uagb-ifb-content .uagb-ifb-left-title-image img{width: 50px;}.uagb-block-0e93844b .uagb-ifb-content .uagb-ifb-right-title-image img{width: 50px;}.uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-2f6d7bb6.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-f7cb0fd8{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f7cb0fd8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-f7cb0fd8{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e72d3f39{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e72d3f39 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e72d3f39{padding-top: 0px;padding-bottom: 0px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.uagb-block-01ee8282.wp-block-uagb-separator{text-align: center;}.uagb-block-01ee8282.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-01ee8282.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-0dff694e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0dff694e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-0dff694e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-0dff694e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-0dff694e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-0dff694e .uagb-ifb-content .uagb-ifb-image-content img{width: 50px;}.uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 50px;}.uagb-block-0dff694e .uagb-ifb-content .uagb-ifb-left-title-image img{width: 50px;}.uagb-block-0dff694e .uagb-ifb-content .uagb-ifb-right-title-image img{width: 50px;}.uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-0dff694e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-96c43cb1.wp-block-uagb-separator{text-align: center;}.uagb-block-96c43cb1.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-96c43cb1.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-8f5bd569 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8f5bd569 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8f5bd569 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-8f5bd569 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-8f5bd569 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-8f5bd569 .uagb-ifb-content .uagb-ifb-image-content img{width: 50px;}.uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 50px;}.uagb-block-8f5bd569 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 50px;}.uagb-block-8f5bd569 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 50px;}.uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-8f5bd569.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-071e7ba8.wp-block-uagb-separator{text-align: center;}.uagb-block-071e7ba8.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-071e7ba8.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-f3907581 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f3907581 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-f3907581 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-f3907581 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-f3907581 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-f3907581 .uagb-ifb-content .uagb-ifb-image-content img{width: 50px;}.uagb-block-f3907581.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 50px;}.uagb-block-f3907581 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 50px;}.uagb-block-f3907581 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 50px;}.uagb-block-f3907581.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-f3907581.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-ae27b54f.wp-block-uagb-separator{text-align: center;}.uagb-block-ae27b54f.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-ae27b54f.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b44d3826 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b44d3826 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b44d3826 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b44d3826 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b44d3826 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b44d3826 .uagb-ifb-content .uagb-ifb-image-content img{width: 50px;}.uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 50px;}.uagb-block-b44d3826 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 50px;}.uagb-block-b44d3826 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 50px;}.uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b44d3826.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8b005355{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8b005355 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-8b005355{padding-top: 0px;padding-bottom: 0px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.uagb-block-8841b8da.wp-block-uagb-separator{text-align: center;}.uagb-block-8841b8da.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-8841b8da.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-9a30308c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9a30308c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-9a30308c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-9a30308c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-9a30308c .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-9a30308c .uagb-ifb-content .uagb-ifb-image-content img{width: 50px;}.uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 50px;}.uagb-block-9a30308c .uagb-ifb-content .uagb-ifb-left-title-image img{width: 50px;}.uagb-block-9a30308c .uagb-ifb-content .uagb-ifb-right-title-image img{width: 50px;}.uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-9a30308c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-8873103c.wp-block-uagb-separator{text-align: center;}.uagb-block-8873103c.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-8873103c.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-732f517a .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-732f517a .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-732f517a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-732f517a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-732f517a .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-732f517a .uagb-ifb-content .uagb-ifb-image-content img{width: 50px;}.uagb-block-732f517a.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 50px;}.uagb-block-732f517a .uagb-ifb-content .uagb-ifb-left-title-image img{width: 50px;}.uagb-block-732f517a .uagb-ifb-content .uagb-ifb-right-title-image img{width: 50px;}.uagb-block-732f517a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-732f517a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-04553612.wp-block-uagb-separator{text-align: center;}.uagb-block-04553612.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-04553612.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-cf35e07d .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cf35e07d .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-cf35e07d .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-cf35e07d .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-cf35e07d .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-cf35e07d .uagb-ifb-content .uagb-ifb-image-content img{width: 50px;}.uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 50px;}.uagb-block-cf35e07d .uagb-ifb-content .uagb-ifb-left-title-image img{width: 50px;}.uagb-block-cf35e07d .uagb-ifb-content .uagb-ifb-right-title-image img{width: 50px;}.uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-cf35e07d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-ea1d1ad3.wp-block-uagb-separator{text-align: center;}.uagb-block-ea1d1ad3.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-ea1d1ad3.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #abb8c3;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-0e93844b .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0e93844b .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-0e93844b .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-0e93844b .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-0e93844b .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-0e93844b .uagb-ifb-content .uagb-ifb-image-content img{width: 50px;}.uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 50px;}.uagb-block-0e93844b .uagb-ifb-content .uagb-ifb-left-title-image img{width: 50px;}.uagb-block-0e93844b .uagb-ifb-content .uagb-ifb-right-title-image img{width: 50px;}.uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-0e93844b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-2f6d7bb6.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:13:{i:0;s:12:\"core\/heading\";i:1;s:11:\"core\/spacer\";i:2;s:14:\"core\/paragraph\";i:3;s:14:\"uagb\/container\";i:5;s:14:\"uagb\/separator\";i:6;s:13:\"uagb\/info-box\";i:7;s:10:\"uagb\/image\";i:8;s:11:\"core\/search\";i:9;s:10:\"core\/group\";i:10;s:17:\"core\/latest-posts\";i:11;s:20:\"core\/latest-comments\";i:12;s:13:\"core\/archives\";i:13;s:15:\"core\/categories\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1784020051\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"],"_uag_css_file_name":["uag-css-62937.css"]},"uagb_featured_image_src":{"full":["https:\/\/www.gonomadu.com\/wp-content\/uploads\/2026\/07\/villa-xabia-4.webp",1838,1225,false],"thumbnail":["https:\/\/www.gonomadu.com\/wp-content\/uploads\/2026\/07\/villa-xabia-4.webp",150,100,false],"medium":["https:\/\/www.gonomadu.com\/wp-content\/uploads\/2026\/07\/villa-xabia-4.webp",300,200,false],"medium_large":["https:\/\/www.gonomadu.com\/wp-content\/uploads\/2026\/07\/villa-xabia-4.webp",768,512,false],"large":["https:\/\/www.gonomadu.com\/wp-content\/uploads\/2026\/07\/villa-xabia-4.webp",1024,682,false],"1536x1536":["https:\/\/www.gonomadu.com\/wp-content\/uploads\/2026\/07\/villa-xabia-4-1536x1024.webp",1536,1024,true],"2048x2048":["https:\/\/www.gonomadu.com\/wp-content\/uploads\/2026\/07\/villa-xabia-4.webp",1838,1225,false],"houzez-gallery":["https:\/\/www.gonomadu.com\/wp-content\/uploads\/2026\/07\/villa-xabia-4-1170x785.webp",1170,785,true],"houzez-top-v7":["https:\/\/www.gonomadu.com\/wp-content\/uploads\/2026\/07\/villa-xabia-4-780x780.webp",780,780,true],"houzez-item-image-6":["https:\/\/www.gonomadu.com\/wp-content\/uploads\/2026\/07\/villa-xabia-4-584x438.webp",584,438,true]},"uagb_author_info":{"display_name":"TRUEStudio","author_link":"https:\/\/www.gonomadu.com\/de\/author\/truestudio\/"},"uagb_comment_info":0,"uagb_excerpt":"Beeindruckende neu gebaute mediterrane Villa mit beheiztem Pool, mehreren Terrassen, Fitnessbereich und Blick auf das Meer und den Montg\u00f3, nur wenige Minuten vom Strand Arenal entfernt. Diese neu gebaute Villa befindet sich in einer erstklassigen Lage in X\u00e0bia, wo das imposante Bergmassiv Montg\u00f3 auf das kristallklare Mittelmeer trifft. Hochwertige Ausstattung, darunter Fu\u00dfbodenheizung, Klimaanlage mit Heiz-&hellip;","_links":{"self":[{"href":"https:\/\/www.gonomadu.com\/de\/wp-json\/wp\/v2\/properties\/62937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gonomadu.com\/de\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/www.gonomadu.com\/de\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/www.gonomadu.com\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":3,"href":"https:\/\/www.gonomadu.com\/de\/wp-json\/wp\/v2\/properties\/62937\/revisions"}],"predecessor-version":[{"id":63005,"href":"https:\/\/www.gonomadu.com\/de\/wp-json\/wp\/v2\/properties\/62937\/revisions\/63005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gonomadu.com\/de\/wp-json\/wp\/v2\/media\/62879"}],"wp:attachment":[{"href":"https:\/\/www.gonomadu.com\/de\/wp-json\/wp\/v2\/media?parent=62937"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/www.gonomadu.com\/de\/wp-json\/wp\/v2\/property_type?post=62937"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/www.gonomadu.com\/de\/wp-json\/wp\/v2\/property_status?post=62937"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/www.gonomadu.com\/de\/wp-json\/wp\/v2\/property_feature?post=62937"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/www.gonomadu.com\/de\/wp-json\/wp\/v2\/property_label?post=62937"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/www.gonomadu.com\/de\/wp-json\/wp\/v2\/property_country?post=62937"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/www.gonomadu.com\/de\/wp-json\/wp\/v2\/property_state?post=62937"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/www.gonomadu.com\/de\/wp-json\/wp\/v2\/property_city?post=62937"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/www.gonomadu.com\/de\/wp-json\/wp\/v2\/property_area?post=62937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}